{"id":1303,"date":"2022-05-27T16:53:20","date_gmt":"2022-05-27T07:53:20","guid":{"rendered":"https:\/\/hardestchoice.org\/?p=1303"},"modified":"2022-05-27T17:45:54","modified_gmt":"2022-05-27T08:45:54","slug":"%e3%83%af%e3%83%bc%e3%82%af%e3%82%b7%e3%83%a7%e3%83%83%e3%83%97%e3%80%8c%e5%ae%87%e5%ae%99%e5%a4%a9%e6%b0%97%e4%ba%88%e5%a0%b1%e3%80%8d%e5%a0%b1%e5%91%8a%e6%9b%b8%e3%82%92%e3%81%bf%e3%82%93%e3%81%aa","status":"publish","type":"post","link":"https:\/\/hardestchoice.org\/pt\/2022\/05\/27\/1303\/","title":{"rendered":"Vamos todos ler o relat\u00f3rio do workshop &quot;Space Weather Forecast&quot;"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Atualmente, o p\u00fablico est\u00e1 respondendo ao projeto de relat\u00f3rio &quot;Rumo \u00e0 concretiza\u00e7\u00e3o de uma sociedade e economia seguras e protegidas em resposta a desastres que envolvem a evolu\u00e7\u00e3o da civiliza\u00e7\u00e3o&quot;, preparado pelo Grupo de Estudo sobre a Sofistica\u00e7\u00e3o do Clima Espacial do Minist\u00e9rio de Assuntos Internos e Comunica\u00e7\u00f5es. Previs\u00e3o: Est\u00e3o a ser solicitados coment\u00e1rios p\u00fablicos aos cidad\u00e3os.<br>O relat\u00f3rio, que \u00e9 exclusivo para o espa\u00e7o e descreve como responder antecipadamente aos fen\u00f3menos meteorol\u00f3gicos espaciais que ocorrem uma vez a cada 100 a 1000 anos, tem uma vasta gama de implica\u00e7\u00f5es, incluindo n\u00e3o s\u00f3 a concep\u00e7\u00e3o de sistemas, mas tamb\u00e9m o desenvolvimento da sociedade e dos recursos humanos. uma men\u00e7\u00e3o de um ponto de vista.<br>Na verdade, li um relat\u00f3rio que se concentra na pol\u00edtica espacial e n\u00e3o no clima espacial.<br>Ao pensar nisso, espero que lhe d\u00ea a oportunidade de pensar mais de perto sobre o clima espacial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">projecto de relat\u00f3rio<br><a href=\"https:\/\/www.soumu.go.jp\/main_content\/000813479.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.soumu.go.jp\/main_content\/000813479.pdf<\/a><br>Link para apostilas da reuni\u00e3o de estudo<br><a href=\"https:\/\/www.soumu.go.jp\/main_sosiki\/kenkyu\/space_weather\/index.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.soumu.go.jp\/main_sosiki\/kenkyu\/space_weather\/index.html<\/a><br>Suposi\u00e7\u00e3o de pior caso<br><a href=\"https:\/\/www.soumu.go.jp\/main_content\/000811921.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.soumu.go.jp\/main_content\/000811921.pdf<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contente<br>Leia o relat\u00f3rio e os materiais da reuni\u00e3o de revis\u00e3o via zoom e identifique quaisquer d\u00favidas que possa ter.<br>Fa\u00e7a uma discuss\u00e3o entre os participantes. As opini\u00f5es que surgirem ser\u00e3o submetidas como coment\u00e1rios p\u00fablicos ao relat\u00f3rio.<br>O organizador ir\u00e1 coletar e enviar todos de uma vez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">data e hora<br>3 de junho (sexta-feira) 20h00-22h00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">lugar<br>On-line (usando zoom)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Capacidade<br>Aproximadamente 20 pessoas (varia um pouco dependendo da situa\u00e7\u00e3o)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">aplicativo<br>Por favor registe-se atrav\u00e9s do formul\u00e1rio abaixo.<br><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdtONDJA7g7R69wVU7pBDKUjxlu5Lj6UUmhdThPjj6L6XYnoA\/viewform?usp=sf_link\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdtONDJA7g7R69wVU7pBDKUjxlu5Lj6UUmhdThPjj6L6XYnoA\/viewform?usp=sf_link<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea receber\u00e1 informa\u00e7\u00f5es de URL de zoom do organizador posteriormente.<br>\u30fbPreparar o relat\u00f3rio preliminar e, se dispon\u00edvel, os materiais para a reuni\u00e3o de revis\u00e3o.<br>Recomendamos que voc\u00ea d\u00ea uma olhada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">zelador<br>Harushi Tamazawa (representante), Yuko Gatai, Hirotsugu Oba, Noiru Kikuchi, Yuki Takagi<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Patrocinado por<br>\u226aEscolha Final\u226b Grupo de Estudo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este workshop \u00e9 apoiado pelos seguintes projetos.<br>Bolsa de Pesquisa da Funda\u00e7\u00e3o Toyota<br>\u201cRequisitos de IA para tomada de decis\u00f5es sociais: pesquisa sobre conjuntos de dados de alta qualidade e resultados desej\u00e1veis\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contato: Tamazawa (tamazawa_atmark_kwasan.kyoto-u.ac.jp)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>\u73fe\u5728\u3001\u7dcf\u52d9\u7701\u30fb\u5b87\u5b99\u5929\u6c17\u4e88\u5831\u306e\u9ad8\u5ea6\u5316\u306e\u5728\u308a\u65b9\u306b\u95a2\u3059\u308b\u691c\u8a0e\u4f1a\u304c\u4f5c\u6210\u3057\u305f\u5831\u544a\u66f8\u300c\u6587\u660e\u9032\u5316\u578b\u306e\u707d\u5bb3\u300d\u306b\u5bfe\u5fdc\u3057\u305f\u5b89\u5168\u30fb\u5b89 [&hellip;]<\/p>\n","protected":false},"author":211230327,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_wpcom_ai_launchpad_first_post":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[124847,124854],"tags":[],"class_list":["post-1303","post","type-post","status-publish","format-standard","hentry","category-124847","category-124854"],"jetpack_publicize_connections":[],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pdK9kd-l1","jetpack-related-posts":[],"amp_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/posts\/1303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/users\/211230327"}],"replies":[{"embeddable":true,"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/comments?post=1303"}],"version-history":[{"count":7,"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/posts\/1303\/revisions"}],"predecessor-version":[{"id":1341,"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/posts\/1303\/revisions\/1341"}],"wp:attachment":[{"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/media?parent=1303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/categories?post=1303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hardestchoice.org\/pt\/wp-json\/wp\/v2\/tags?post=1303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}